{"id":219357,"date":"2022-10-24T11:06:26","date_gmt":"2022-10-24T08:06:26","guid":{"rendered":"https:\/\/uacrisis.org\/u-mariupoli"},"modified":"2022-11-05T15:15:37","modified_gmt":"2022-11-05T13:15:37","slug":"u-mariupoli","status":"publish","type":"post","link":"https:\/\/uacrisis.org\/fr\/u-mariupoli","title":{"rendered":"&#8220;Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol&#8221;"},"content":{"rendered":"\n<p><strong>&#8220;On voit des gens qui sont encore en vie, bien qu&#8217;ils n&#8217;aient pas de t\u00eate ; on voit des soldats courir, alors qu&#8217;on leur a coup\u00e9 les deux pieds ; ils boitillent sur leurs moignons avec des \u00e9clats d&#8217;os qui d\u00e9passent jusqu&#8217;\u00e0 la br\u00e8che la plus proche ; un caporal a ramp\u00e9 deux kilom\u00e8tres sur ses mains, tra\u00eenant derri\u00e8re lui ses jambes cass\u00e9es ; un autre va au poste de secours, pressant ses mains sur son ventre, pour faire rentrer ses intestins rampant\u202f; on voit des gens sans l\u00e8vres, sans m\u00e2choire inf\u00e9rieure, sans visage ; on ramasse un soldat qui, pendant deux heures, a serr\u00e9 une art\u00e8re de son bras avec ses dents pour l&#8217;emp\u00eacher de saigner ; le soleil se l\u00e8ve, la nuit tombe, les obus sifflent, la vie est finie.&#8221;<\/strong><\/p>\n\n\n\n<p><strong>Vous croyez que c&#8217;est un reportage sur la guerre russo-ukrainienne\u202f? Vous vous trompez. Il s&#8217;agit d&#8217;un extrait du roman de Remarque. Il d\u00e9crit parfaitement l&#8217;atmosph\u00e8re des combats. L&#8217;h\u00e9ro\u00efne de notre histoire vous dira qu&#8217;il y a pire. Lorsque l&#8217;esprit de guerre sort des tranch\u00e9es, \u00e0 la recherche de nouvelles victimes, et vole au-dessus de la grande ville, essayant de la couvrir avec ses ailes noires. Dans ces moments-l\u00e0, vous r\u00e9alisez que vous \u00eates en enfer.<\/strong><\/p>\n\n\n\n<p><strong>Pour Daria Markovytch, ces minutes se fondaient dans les jours de plomb. Quand elle a accept\u00e9 cet entretien, des larmes ont commenc\u00e9 \u00e0 couler sur ses joues. Apr\u00e8s de telles \u00e9motions, j&#8217;\u00e9tais m\u00eame g\u00ean\u00e9e de poser des questions sur ce qu&#8217;elle a v\u00e9cu \u00e0 Marioupol.&nbsp; Mais je n&#8217;ai pas eu \u00e0 en poser beaucoup, juste apr\u00e8s la premi\u00e8re question, la jeune femme a commenc\u00e9 \u00e0 parler ouvertement avec des d\u00e9tails horribles sur trois semaines de survie dans la ville. Pour elle, cette conversation n&#8217;est pas seulement une r\u00e9flexion, c&#8217;est le d\u00e9sir de crier, pour que le monde entende sa voix. &#8220;Je le fais parce que je veux que les gens soient au courant. Je veux qu&#8217;ils soient au courant des crimes russes et l&#8217;enfer par lequel les habitants de Marioupol ont d\u00fb passer en mars 2022.&nbsp;\u00bb D\u00e9sol\u00e9e, mais \u00e7a va \u00eatre douloureux.<\/strong><\/p>\n\n\n\n<h3><strong><strong>&#8220;EN QUELQUES JOURS, IL N&#8217;\u00c9TAIT PLUS POSSIBLE DE QUITTER LA VILLE PAR LES CHEMINS DE FER, ET VOLNOVAKHA A \u00c9T\u00c9 EFFAC\u00c9E DE LA CARTE&#8221;<\/strong><\/strong><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 303 453'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Darya-Markovych-bilya-golovnoyi-yalynky-u-Mariupoli-683x1024.jpg\" alt=\"\" class=\"lazyload wp-image-218625\" width=\"303\" height=\"453\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Darya-Markovych-bilya-golovnoyi-yalynky-u-Mariupoli-683x1024.jpg 683w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Darya-Markovych-bilya-golovnoyi-yalynky-u-Mariupoli-200x300.jpg 200w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Darya-Markovych-bilya-golovnoyi-yalynky-u-Mariupoli-scaled.jpg 1707w\" data-sizes=\"(max-width: 303px) 100vw, 303px\" \/><\/figure><\/div>\n\n\n\n<p>\u00c0 la veille du 24 f\u00e9vrier, Daria et ses proches, bien s\u00fbr, lisaient les informations et \u00e9taient au courant du resserrement des troupes russes le long des fronti\u00e8res. La direction de Dasha a discut\u00e9 avec ses coll\u00e8gues des options au cas o\u00f9 \u00ab&nbsp;et si cela se produisait&nbsp;\u00bb, les gens pr\u00e9paraient des valises de secours, pensaient \u00e0 un plan d&#8217;\u00e9vacuation. Cependant, comme le dit la jeune fille, elle et beaucoup d&#8217;habitants de Marioupol &#8220;n&#8217;y pr\u00eataient pas vraiment attention&#8221;, parce que des explosions retentissaient d\u00e9j\u00e0 dans la ville et dans la banlieue depuis 2014, donc les locaux s&#8217;y sont habitu\u00e9s.&nbsp; Ils pensaient que rien d&#8217;horrible ne pouvait arriver. Il s&#8217;est av\u00e9r\u00e9 qu&#8217;ils se trompaient.<\/p>\n\n\n\n<p>Ce matin-l\u00e0, Daria n&#8217;a pas \u00e9t\u00e9 r\u00e9veill\u00e9e par les explosions. \u00c0 ce moment-l\u00e0, elle arrivait encore \u00e0 bien dormir. Elle a \u00e9t\u00e9 r\u00e9veill\u00e9e par l&#8217;appel d&#8217;un coll\u00e8gue :<\/p>\n\n\n\n<p>&#8211; All\u00f4, Dasha, qu&#8217;est-ce que tu vas faire ?&nbsp;<\/p>\n\n\n\n<p>&#8211; Comment \u00e7a ?<\/p>\n\n\n\n<p>&#8211; Quoi, tu n&#8217;es pas au courant ? La guerre a commenc\u00e9.<\/p>\n\n\n\n<p>L&#8217;horloge affichait 7h15. Dans la cuisine, maman pr\u00e9parait le petit d\u00e9jeuner. La jeune fille a d\u00e9cid\u00e9 d&#8217;allumer la t\u00e9l\u00e9 et a commenc\u00e9 \u00e0 trembler.<\/p>\n\n\n\n<p>Les coll\u00e8gues et les amis appelaient, discutaient de ce qu&#8217;il fallait faire. Certains sont partis avec leur voiture, d&#8217;autres ont pay\u00e9 des sommes astronomiques, 1000 euros pour aller \u00e0 Dnipro en taxi. Mais tout fonctionnait : l&#8217;\u00e9lectricit\u00e9, l&#8217;eau, le gaz, Internet et le r\u00e9seau, et nous sommes d\u00e9j\u00e0 pass\u00e9s par \u00e7a en 2014.<\/p>\n\n\n\n<p>&#8220;Je vivais dans le quartier Kalmiouskyi. Pr\u00e8s de chez moi, il y avait une piscine municipale sur le point d&#8217;ouvrir et un h\u00f4pital militaire. Les fen\u00eatres de mon appartement donnaient une vue sur l&#8217;usine m\u00e9tallurgique &#8220;Azovstal&#8221;. J&#8217;ai sugg\u00e9r\u00e9 \u00e0 maman de partir, mais elle ne voulait pas. Elle disait que si les fen\u00eatres explosaient, nous les r\u00e9parerions, et si la maison br\u00fblait, nous l&#8217;\u00e9teindrions. En plus, ma m\u00e8re jouait dans un orchestre et elle m&#8217;a dit qu&#8217;elle n&#8217;avait pas pris ses violons de la Philharmonie et de l&#8217;\u00e9cole de musique, et que sans eux, elle n&#8217;irait nulle part. Maman a trouv\u00e9 un million de raisons de rester&#8221;.<\/p>\n\n\n\n<p>Les femmes restaient dans les appartements avec leur chat et l&#8217;espoir que le probl\u00e8me les contournera.<\/p>\n\n\n\n<p>&#8220;Le quartier Est a d\u00e9j\u00e0 \u00e9t\u00e9 bombard\u00e9, et je suis all\u00e9e l\u00e0-bas chez des amis. Leur b\u00e2timent a \u00e9t\u00e9 frapp\u00e9 par un missile et ils avaient besoin de scotch pour les fen\u00eatres. Les gens l\u00e0-bas couraient dans la panique, arr\u00eataient les voitures pour partir d&#8217;une mani\u00e8re ou d&#8217;une autre. J&#8217;ai emmen\u00e9 deux familles \u00e0 la gare. \u00c0 l&#8217;\u00e9poque, il y avait toujours le train pour Kyiv. Marioupol est une gare ferroviaire sans issue. Pr\u00e8s de nous se trouve Volnovakha, o\u00f9 il y avait d\u00e9j\u00e0 eu de lourds combats. En quelques jours, il n&#8217;\u00e9tait plus possible de quitter la ville par les chemins de fer, et Volnovakha a \u00e9t\u00e9 effac\u00e9e de la carte. Le 27 ou le 28 f\u00e9vrier, le dernier train d&#8217;\u00e9vacuation a quitt\u00e9 la gare et la route vers Volnovakha a \u00e9t\u00e9 compl\u00e8tement bombard\u00e9e.&#8221;<\/p>\n\n\n\n<h3><strong><strong>&#8220;J&#8217;AI R\u00c9ALIS\u00c9 QUE \u00c7A POURRAIT \u00caTRE MON DERNIER ANNIVERSAIRE. J&#8217;AI F\u00caT\u00c9 MES 30 ANS SOUS LES BOMBARDEMENTS&#8221;<\/strong><\/strong><\/h3>\n\n\n\n<p>La ville s&#8217;est activement impliqu\u00e9e dans le b\u00e9n\u00e9volat. Les gens apportaient des v\u00eatements chauds et des couvertures aux victimes, faisaient la queue pour donner du sang, collectaient des fonds et, lorsque les supermarch\u00e9s fonctionnaient, achetaient de la nourriture pour nos soldats. Une semaine plus tard, ils cherchaient de la nourriture pour eux-m\u00eames.<\/p>\n\n\n\n<p>&#8220;J&#8217;ai fait du b\u00e9n\u00e9volat, aid\u00e9 avec tout ce que je pouvais. Jusqu&#8217;au 1er mars, les sir\u00e8nes sonnaient toujours, puis l&#8217;\u00e9lectricit\u00e9 a \u00e9t\u00e9 coup\u00e9e, puis les communications. C&#8217;\u00e9tait effrayant de sortir. Je comptais sur le fait que les magasins \u00e9taient ouverts et qu&#8217;il y avait de la nourriture l\u00e0-bas. Nous n&#8217;avions pas fait de stocks s\u00e9rieux de nourriture. C&#8217;est un miracle que quelques jours avant le d\u00e9but de la guerre \u00e0 grande \u00e9chelle, j&#8217;ai achet\u00e9 un stock de 2 kilogrammes de nourriture pour mon chat. M\u00eame si je n&#8217;avais jamais fait \u00e7a avant. Cela l&#8217;a aid\u00e9 \u00e0 survivre.<\/p>\n\n\n\n<p>Le 5 mars, c&#8217;est l&#8217;anniversaire de Dasha, alors elle a d\u00e9cid\u00e9 avec son amie d&#8217;aller faire du shopping pour acheter quelque chose pour les f\u00eates.<\/p>\n\n\n\n<p>&#8220;Pour moi, f\u00eater mon anniversaire a toujours \u00e9t\u00e9 un rituel sp\u00e9cial lorsque je rassemblais toutes les personnes qui m&#8217;\u00e9taient ch\u00e8res. Et je savais que \u00e7a pourrait \u00eatre mon dernier anniversaire. Je voulais vraiment voir les visages de ma famille, tenir leur main. Je voulais me souvenir de chaque jour et faire quelque chose qui puisse plaire&#8221;.<\/p>\n\n\n\n<p>Quelques jours auparavant, Dasha avait r\u00e9ussi \u00e0 retirer 80 euros en esp\u00e8ces, apr\u00e8s les guichets automatiques ont cess\u00e9 de fonctionner.<\/p>\n\n\n\n<p>&#8220;Nous avons vu comment les fen\u00eatres et les portes dans tous les magasins sont explos\u00e9es et le pillage commence. Sous nos yeux, les fen\u00eatres \u00e9taient d\u00e9truites par des soldats. Ils comprenaient que la ville \u00e9tait d\u00e9j\u00e0 assi\u00e9g\u00e9e et qu&#8217;il n&#8217;y aurait pas d&#8217;aide. Et s&#8217;ils ne le font pas, les gens vont piller de mani\u00e8re incontr\u00f4lable. Ils prenaient vraiment tout&nbsp;: des machines \u00e0 laver jusqu&#8217;aux t\u00e9l\u00e9phones. Les militaires arr\u00eataient ceux qui prenaient de l&#8217;alcool et brisaient les bouteilles. C&#8217;\u00e9tait une horreur. Comme un film d&#8217;Apocalypse zombie&nbsp;: les gens aux yeux vides grimpent sur les comptoirs et prennent tout ce qu&#8217;ils voient. Mais nous voulions acheter\u202f! On avait de l&#8217;argent\u202f! Mais personne n&#8217;avait besoin d&#8217;argent. C&#8217;est un \u00e9tat \u00e9trange&nbsp;: vous r\u00e9alisez que vous avez de l&#8217;argent, mais vous ne pouvez pas acheter de m\u00e9dicaments, \u00e0 manger ou de nourriture pour chat. L&#8217;argent s&#8217;est d\u00e9pr\u00e9ci\u00e9 et l&#8217;\u00e9change de biens a commenc\u00e9. Les cigarettes sont devenues la nouvelle monnaie&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1.jpg\"><img loading=\"lazy\" width=\"1280\" height=\"960\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 1280 960'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1.jpg\" alt=\"\" data-id=\"218613\" data-full-url=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1.jpg\" data-link=\"https:\/\/uacrisis.org\/?attachment_id=218613\" class=\"lazyload wp-image-218613\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1.jpg 1280w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-300x225.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-1024x768.jpg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-768x576.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-90x67.jpg 90w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-180x135.jpg 180w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-265x199.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-531x398.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-608x456.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-1-758x569.jpg 758w\" data-sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo.jpg\"><img loading=\"lazy\" width=\"720\" height=\"1280\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 720 1280'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo.jpg\" alt=\"\" data-id=\"218619\" data-full-url=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo.jpg\" data-link=\"https:\/\/uacrisis.org\/?attachment_id=218619\" class=\"lazyload wp-image-218619\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo.jpg 720w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-169x300.jpg 169w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-576x1024.jpg 576w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-265x471.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-531x944.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Maroderstvo-608x1081.jpg 608w\" data-sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Apr\u00e8s cela, des bombardements intenses ont commenc\u00e9, des avions volaient au loin, des b\u00e2timents ont commenc\u00e9 \u00e0 br\u00fbler.<\/p>\n\n\n\n<p>&#8220;C&#8217;est tr\u00e8s effrayant de faire le tour de la ville et de voir les maisons br\u00fbler comme des bougies, car il n&#8217;y a pas d&#8217;eau pour les \u00e9teindre. J&#8217;ai f\u00eat\u00e9 mes 30 ans au sous-sol sous les bombardements. Maman avait une bouteille de vin qui nous remontait un peu le moral&#8221;.<\/p>\n\n\n\n<h3><strong><strong>&#8220;NOTRE MENTAL NE POUVAIT PLUS SUPPORTER. LES GENS SE JETAIENT PAR LA FEN\u00caTRE&#8221;<\/strong><\/strong><\/h3>\n\n\n\n<p>On avait promis aux gens de les \u00e9vacuer. Ils attendaient dans le froid, mais les Russes n&#8217;ont jamais donn\u00e9 de couloirs pour l&#8217;\u00e9vacuation. Certains conduisaient \u00e0 leurs risques et p\u00e9rils, beaucoup ont \u00e9t\u00e9 abattus sur le chemin.<\/p>\n\n\n\n<p>&#8220;J&#8217;\u00e9tais d\u00e9vast\u00e9e, je pleurais constamment, j&#8217;avais tr\u00e8s peur. J&#8217;ai essay\u00e9 de ne pas pleurer devant ma m\u00e8re. Je suis all\u00e9e dans ma chambre et le soir, j&#8217;\u00e9tais hyst\u00e9rique&#8221;.<\/p>\n\n\n\n<p>Un jour, Daria a \u00e9t\u00e9 appel\u00e9e par une voix masculine famili\u00e8re. C&#8217;\u00e9tait son ex-petit ami. Dans le quartier Est, le b\u00e2timent de ses parents a \u00e9t\u00e9 frapp\u00e9 deux fois. Ils ont donc demand\u00e9 \u00e0 rester vivre un certain temps avec Dasha et sa m\u00e8re.<\/p>\n\n\n\n<p>&#8220;Et les avions ne volaient pas encore ici. Nous n&#8217;avions pas encore r\u00e9alis\u00e9 que les avions \u00e9taient la chose la plus terrible qui puisse arriver dans notre vie.<\/p>\n\n\n\n<p>D\u00e9sormais, Dasha avec sa m\u00e8re et son chat, son amie et son ex avec sa famille vivaient ensemble dans l&#8217;appartement, puis dans le sous-sol. Ils apprenaient les informations gr\u00e2ce au &#8220;bouche-\u00e0-oreille&#8221;. Quand quelqu&#8217;un entendait ou voyait quelque chose, ils rapportaient l&#8217;information, car il n&#8217;y avait plus de r\u00e9seau. Mais il y avait de l&#8217;espoir. L&#8217;espoir que la ville survivrait.<\/p>\n\n\n\n<p>Dans le quartier o\u00f9 Dasha vivait, des combats de rue commen\u00e7aient, des chars circulaient, des gens commen\u00e7aient \u00e0 mourir&nbsp;: naturellement d&#8217;un arr\u00eat cardiaque, d&#8217;un accident vasculaire c\u00e9r\u00e9bral, d&#8217;un manque de m\u00e9dicaments et de raisons non-naturelles&nbsp;: d\u00e9chir\u00e9s par les fragments de missiles, br\u00fbl\u00e9s vivants dans des incendies, \u00e9cras\u00e9s sous les d\u00e9combres des maisons et autres.<\/p>\n\n\n\n<p>&#8220;Il y en avait beaucoup qui finissaient par se suicider, les gens se jetaient par la fen\u00eatre. Notre mental ne pouvait plus supporter, m\u00eame chez les jeunes. Et que dire des retrait\u00e9s seuls&#8230;&#8221;<\/p>\n\n\n\n<p>Il faisait tr\u00e8s froid. Il n&#8217;y avait plus de gaz et, pour survivre, les gens ont commenc\u00e9 \u00e0 d\u00e9monter les cl\u00f4tures, \u00e0 br\u00fbler des livres et des meubles. Des cuisines ext\u00e9rieures \u00e9taient dans chaque cour, les gens se relayaient pour maintenir le feu.<\/p>\n\n\n\n<p>&#8220;Nous avons eu une cour tr\u00e8s amicale : tout le monde se partageait la nourriture, certains d\u00e9congelaient de la viande ou du lait, d&#8217;autres r\u00e9ussissaient \u00e0 se procurer quelque chose. L&#8217;alcool des stocks domestiques \u00e9tait \u00e9galement partag\u00e9, car nous avions tr\u00e8s peur et froid, il \u00e9tait impossible de s&#8217;endormir.<\/p>\n\n\n\n<p>Il \u00e9tait n\u00e9cessaire de se procurer de l&#8217;eau \u00e9galement. \u00c0 partir du 6 mars, Dasha avec son amie et son ex-petit ami ont commenc\u00e9 \u00e0 aller chercher de l&#8217;eau au ruisseau. Elle \u00e9tait tr\u00e8s sale, mais pour laver les toilettes cela convenait. Par la suite, ils ont trouv\u00e9 un puits avec de l&#8217;eau potable seulement apr\u00e8s \u00e9bullition.<\/p>\n\n\n\n<p>&#8220;Tu fais la queue pour l&#8217;eau, et \u00e0 quelques m\u00e8tres de toi une mine explose&#8230; quelqu&#8217;un est d\u00e9chir\u00e9 en morceaux, quelqu&#8217;un est bless\u00e9 ou tu\u00e9 par des d\u00e9bris, quelqu&#8217;un a des tympans \u00e9clat\u00e9s&#8230; il y a un bras et une jambe, qui gisent sur le sol. Et ils doivent \u00eatre enterr\u00e9s, parce que des grands-m\u00e8res, et des enfants viennent ici. Ils ne doivent pas voir cela. Tu essaies de faire abstraction, de penser que c&#8217;est juste de la viande, que ce n&#8217;est pas un \u00eatre humain. Et m\u00eame involontairement, tu te dis que la viande humaine ressemble beaucoup \u00e0 du porc. Mais la nuit, les pens\u00e9es et les images te rattrapent. Je n&#8217;ai pas parl\u00e9 \u00e0 ma m\u00e8re de toutes les personnes qu&#8217;on enterrait. Mais il n&#8217;y a pas d&#8217;autre endroit pour prendre de l&#8217;eau. Et tu dois revenir ici le lendemain. Parce qu&#8217;il est possible de manger tous les deux jours, mais on a quand m\u00eame envie de boire&#8221;.<\/p>\n\n\n\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-has-lightbox su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-none\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":true,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":false,\"autoPlay\":false,\"imagesLoaded\":true,\"contain\":false,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a56e1c6ada00\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348.jpg\" data-caption=\"\"><img width=\"1280\" height=\"960\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348.jpg 1280w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-300x225.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-1024x768.jpg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-768x576.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-90x67.jpg 90w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-180x135.jpg 180w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-265x199.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-531x398.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-608x456.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0348-758x569.jpg 758w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350.jpg\" data-caption=\"\"><img width=\"1280\" height=\"960\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350.jpg 1280w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-300x225.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-1024x768.jpg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-768x576.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-90x67.jpg 90w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-180x135.jpg 180w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-265x199.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-531x398.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-608x456.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0350-758x569.jpg 758w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351.jpg\" data-caption=\"\"><img width=\"960\" height=\"1280\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351.jpg 960w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-225x300.jpg 225w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-768x1024.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-265x353.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-531x708.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-608x811.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0351-758x1011.jpg 758w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352.jpg\" data-caption=\"\"><img width=\"1024\" height=\"682\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352.jpg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-300x200.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-768x512.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-180x120.jpg 180w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-265x176.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-531x354.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-608x405.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0352-758x505.jpg 758w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353.jpg\" data-caption=\"\"><img width=\"1280\" height=\"960\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353.jpg 1280w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-300x225.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-1024x768.jpg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-768x576.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-90x67.jpg 90w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-180x135.jpg 180w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-265x199.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-531x398.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-608x456.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0353-758x569.jpg 758w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354.jpg\" data-caption=\"\"><img width=\"720\" height=\"1280\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354.jpg 720w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354-169x300.jpg 169w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354-576x1024.jpg 576w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354-265x471.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354-531x944.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0354-608x1081.jpg 608w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355.jpg\" data-caption=\"\"><img width=\"720\" height=\"1280\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355.jpg 720w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355-169x300.jpg 169w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355-576x1024.jpg 576w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355-265x471.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355-531x944.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/IMG_0355-608x1081.jpg 608w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/div><\/div><\/div><script id=\"su_image_carousel_6a56e1c6ada00_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a56e1c6ada00\"))}, 0);}var su_image_carousel_6a56e1c6ada00_script=document.getElementById(\"su_image_carousel_6a56e1c6ada00_script\");if(su_image_carousel_6a56e1c6ada00_script){su_image_carousel_6a56e1c6ada00_script.parentNode.removeChild(su_image_carousel_6a56e1c6ada00_script);}<\/script>\n\n\n\n<h3><strong><strong>&#8220;ON NE POUVAIT PASSER QU&#8217;EN TRAVERSANT DES CADAVRES&#8221;<\/strong><\/strong><\/h3>\n\n\n\n<p>Le 12 mars, on apprend qu&#8217;il y a du r\u00e9seau au centre-ville. Les avions volaient, mais Dasha et ses amis sont all\u00e9s l\u00e0-bas.<\/p>\n\n\n\n<p>&#8220;Ce jour-l\u00e0, la ville a \u00e9t\u00e9 bombard\u00e9e. Tu ne peux pas confondre le son d&#8217;un avion avec quoi que ce soit. D&#8217;abord, il vole et regarde o\u00f9 jeter la bombe, puis largue. Lorsque nous marchions, nous voyions beaucoup de crat\u00e8res, dus \u00e0 des bombes a\u00e9riennes, de voitures renvers\u00e9es, de vitres bris\u00e9es, d&#8217;arbres arrach\u00e9s \u00e0 leurs racines. Il y avait beaucoup de morts, que personne ne ramassait\u202f; de maisons d\u00e9truites, dont, comme les c\u00f4tes d&#8217;un squelette, il ne restait que des murs porteurs. Tu comprends que des gens sont morts sous les d\u00e9combres. Mais quand ils bombardent avec des bombes au phosphore, rien ne peut te sauver, il ne reste plus rien \u00e0 l&#8217;int\u00e9rieur, plus de lit, plus de r\u00e9frig\u00e9rateurs, plus personne.<\/p>\n\n\n\n<p>J&#8217;ai vu comment des fosses communes \u00e9taient creus\u00e9es. Ensuite, nous avons enterr\u00e9 des gens pr\u00e8s des immeubles. La terre gel\u00e9e \u00e9tait fondue \u00e0 l&#8217;aide d&#8217;un feu de camp, puis des tombes \u00e9taient creus\u00e9es. Quand les premi\u00e8res s\u00e9pultures sont apparues dans les cours, c&#8217;\u00e9tait tr\u00e8s effrayant. Effrayant, comme dans les films d&#8217;horreur. Mais en deux jours, tu t&#8217;y habitues. Tu marches dans la ville et tu vois des tombes dans chaque cour, dans chaque terrain de jeu pour enfants. Et maintenant, quand les parents sont morts, la police a demand\u00e9 d&#8217;amener les corps sur les balcons, parce qu&#8217;il faisait encore froid. Le Marioupol que je connais n&#8217;\u00e9tait plus l\u00e0.<\/p>\n\n\n\n<p>Pendant que nous allions chercher du r\u00e9seau, il y avait des moments o\u00f9 nous ne pouvions passer qu&#8217;en enjambant des cadavres. Tu penses que tu ne vas pas regarder, mais tu regardes. Tu regardes d&#8217;abord sous tes pieds pour ne pas marcher dessus, puis tu ne peux pas d\u00e9tourner les yeux. \u00c0 ce moment-l\u00e0, j&#8217;\u00e9tais choqu\u00e9e. Ces bouleversements \u00e9motionnels \u00e9taient retard\u00e9s dans mon esprit et le soir, je sombrais dans la folie&#8221;.<\/p>\n\n\n\n<p>Nous avons fait le tour de la maternit\u00e9, o\u00f9 les Russes ont largu\u00e9 des bombes trois jours avant, et les photos d&#8217;ici ont fait le tour du monde. Il ne reste rien du b\u00e2timent du bureau de poste principal. Une rue large de 6 routes qui se croisent a \u00e9t\u00e9 enti\u00e8rement bombard\u00e9e apr\u00e8s les explosions de bombes a\u00e9riennes. Dans le centre-ville, des fils \u00e9lectriques \u00e9taient suspendus, des poteaux arrach\u00e9s.<\/p>\n\n\n\n<p>&#8220;Le t\u00e9l\u00e9phone n&#8217;avait presque plus de batterie. Mais quand les premi\u00e8res divisions du r\u00e9seau sont apparues, c&#8217;\u00e9tait tellement \u00e9motionnel ! Nos mains tremblaient. Et puis des SMS ont commenc\u00e9 \u00e0 arriver en russe : &#8220;Ukrofasciste ! Le si\u00e8ge se r\u00e9tr\u00e9cit ! Il ne te reste que quelques heures \u00e0 vivre !&#8221; Ce n&#8217;est pas quelque chose que vous voulez voir lorsque vous allumez votre t\u00e9l\u00e9phone.<\/p>\n\n\n\n<p>Dariya a r\u00e9ussi \u00e0 appeler deux personnes&nbsp;: son petit ami, Dmytro, qui \u00e9tait dans la r\u00e9gion de Tchernihiv et se pr\u00e9parait \u00e0 aller chez elle \u00e0 Marioupol pour la sauver.<\/p>\n\n\n\n<p>&#8220;J&#8217;ai cri\u00e9 que j&#8217;\u00e9tais en vie et j&#8217;ai pleur\u00e9. J&#8217;\u00e9tais tr\u00e8s heureuse d&#8217;entendre sa voix&#8221;.<\/p>\n\n\n\n<p>La seconde \u00e9tait la dirigeante du &#8220;Conseil des femmes de la r\u00e9gion de Donetsk&#8221; et de l&#8217;Union de la jeunesse de Marioupol, dont fait partie Dariya. &#8220;Elle m&#8217;a dit de faire tout pour quitter la ville, elle m&#8217;attend et m&#8217;aidera pour tout. J&#8217;ai dit qu&#8217;il n&#8217;y avait pas de r\u00e9seau, qu&#8217;il y avait des rumeurs selon lesquelles Kyiv aurait \u00e9t\u00e9 prise et nous aurions tous \u00e9t\u00e9 abandonn\u00e9s. Elle m&#8217;a convaincu que ce n&#8217;\u00e9tait pas le cas, mais la situation est critique, la ville est encercl\u00e9e. Mais il y a une route \u00e0 travers les villages vers Berdyansk, Valsylivka et Zaporizhzhya. Il y a d\u00e9j\u00e0 des gens qui ont pu partir de cette mani\u00e8re&#8221;.<\/p>\n\n\n\n<p>La jeune fille a fait des captures d&#8217;\u00e9cran des titres d&#8217;informations pour transmettre au moins quelques nouvelles \u00e0 la maison.<\/p>\n\n\n\n<p>Sur le chemin du retour, Dasha a \u00e9t\u00e9 choqu\u00e9e par un nouveau crat\u00e8re d&#8217;une bombe a\u00e9rienne sur l&#8217;emplacement d&#8217;un b\u00e2timent priv\u00e9 de deux \u00e9tages, qui \u00e9tait encore l\u00e0 r\u00e9cemment. Derri\u00e8re son dos, un bombardement a commenc\u00e9.<\/p>\n\n\n\n<p>&#8220;Les gens sont all\u00e9s \u00e0 notre rencontre et ont dit qu&#8217;il y avait beaucoup de cadavres devant et nous ont averti de ne pas regarder ou contourner. Nous \u00e9tions \u00e0 mi-chemin quand un avion a commenc\u00e9 \u00e0 voler. Il a largu\u00e9 une bombe a\u00e9rienne \u00e0 700 m\u00e8tres de nous. Tout tremble, tu commences \u00e0 paniquer, et soit tu restes l\u00e0 et tu meurs, soit tu commences \u00e0 courir. Nous nous sommes r\u00e9fugi\u00e9s au sous-sol du supermarch\u00e9 pill\u00e9 et avons senti des ondes de choc suite aux explosions. \u00c0 la maison, on a montr\u00e9 les photos de la ville d\u00e9truite et nous avons racont\u00e9 les nouvelles. Pendant que tu es assis dans la cour de ton quartier, tu penses que les choses ne sont pas si terribles ici, que tout est comme \u00e7a partout. Mais tu sors en ville, tu vois que la ville n&#8217;est plus l\u00e0, et tout se retourne dans ta t\u00eate. C&#8217;est une peur animale&#8221;.<\/p>\n\n\n\n<p>Lorsque les occupants ont frapp\u00e9 la piscine municipale, la r\u00e9tine de l&#8217;\u0153il de la m\u00e8re de Daria s&#8217;est d\u00e9tach\u00e9e suite \u00e0 l&#8217;onde explosive. Les fen\u00eatres de l&#8217;appartement ont explos\u00e9.&nbsp; \u00c0 travers le verre bris\u00e9, l&#8217;usine &#8220;Azovstal&#8221; \u00e9tait visible, qui \u00e9tait intens\u00e9ment bombard\u00e9e et&nbsp;&#8220;arros\u00e9e&#8221; de bombes au phosphore, il y avait tout le temps quelque chose qui br\u00fblait et explosait.<\/p>\n\n\n\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-has-lightbox su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-none\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":true,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":false,\"autoPlay\":false,\"imagesLoaded\":true,\"contain\":false,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a56e1c6aec17\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun.jpg\" data-caption=\"\"><img width=\"960\" height=\"1280\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun.jpg 960w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-225x300.jpg 225w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-768x1024.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-265x353.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-531x708.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-608x811.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Zrujnovanyj-Neptun-758x1011.jpg 758w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin.jpg\" data-caption=\"\"><img width=\"1218\" height=\"2092\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin.jpg 1218w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-175x300.jpg 175w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-596x1024.jpg 596w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-768x1319.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-265x455.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-531x912.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-608x1044.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-skrin-758x1302.jpg 758w\" sizes=\"(max-width: 1218px) 100vw, 1218px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun.jpg\" data-caption=\"\"><img width=\"960\" height=\"1280\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun.jpg 960w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-225x300.jpg 225w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-768x1024.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-265x353.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-531x708.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-608x811.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Neptun-758x1011.jpg 758w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/div><\/div><\/div><script id=\"su_image_carousel_6a56e1c6aec17_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a56e1c6aec17\"))}, 0);}var su_image_carousel_6a56e1c6aec17_script=document.getElementById(\"su_image_carousel_6a56e1c6aec17_script\");if(su_image_carousel_6a56e1c6aec17_script){su_image_carousel_6a56e1c6aec17_script.parentNode.removeChild(su_image_carousel_6a56e1c6aec17_script);}<\/script>\n\n\n\n<p>Selon Daria, d&#8217;habitude, de 11 heures \u00e0 2 heures du matin, l&#8217;avion larguait des bombes, jusqu&#8217;\u00e0 4-5 heures du matin, la situation se calmait, et de 5 \u00e0 9 heures du matin, ils bombardaient \u00e0 nouveau. La jeune fille se souvient que le 16 mars \u00e9tait une matin\u00e9e tr\u00e8s calme. Il n&#8217;y a pas eu de tirs ni d&#8217;explosions. Les voisins ont dit qu&#8217;il y avait du r\u00e9seau au dernier \u00e9tage d&#8217;un b\u00e2timent \u00e0 c\u00f4t\u00e9 de 12 \u00e9tages.<\/p>\n\n\n\n<p>&#8220;Nous \u00e9tions au premier \u00e9tage du b\u00e2timent de 12 \u00e9tages, lorsqu&#8217;un bombardement aux lance-roquettes multiples &#8220;Grad&#8221; a commenc\u00e9. Il y a un syst\u00e8me int\u00e9ressant de couloirs, on pouvait se cacher. Tout l&#8217;immeuble tremblait. C&#8217;est la premi\u00e8re fois que j&#8217;ai cri\u00e9 de peur. Nous sommes sortis 20 minutes plus tard et avons vu que les derniers \u00e9tages \u00e9taient d\u00e9truits, que les voitures \u00e9taient en feu. Mon b\u00e2timent est \u00e0 2 minutes \u00e0 pied de celui-ci. Nous avons ramp\u00e9 20 minutes de sous-sol en sous-sol. Les b\u00e2timents autour n&#8217;avaient plus de fen\u00eatres, les balcons s&#8217;\u00e9taient effondr\u00e9s. Nous avons entendu les cris et les pleurs des gens dans les sous-sols qui n&#8217;ont pas encore eu le temps de comprendre ce qui se passait. C&#8217;\u00e9tait la derni\u00e8re goutte&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"957\" height=\"1280\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 957 1280'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022.jpg\" alt=\"\" class=\"lazyload wp-image-218683\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022.jpg 957w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-224x300.jpg 224w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-766x1024.jpg 766w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-768x1027.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-265x354.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-531x710.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-608x813.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/12-poverhivka-de-Dashu-zastav-obstril.-Tak-vona-vyglyadala-koly-divchata-z-neyi-vybigly.-Foto-lito-2022-758x1014.jpg 758w\" data-sizes=\"(max-width: 957px) 100vw, 957px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"960\" height=\"1280\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 960 1280'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly.jpg\" alt=\"\" class=\"lazyload wp-image-218707\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly.jpg 960w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-225x300.jpg 225w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-768x1024.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-265x353.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-531x708.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-608x811.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Obvaleni-balkony-i-zrujnovani-pidvaly-758x1011.jpg 758w\" data-sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<h3><strong><strong>LE DERNIER VIOLON DE MARIOUPOL<\/strong><\/strong><\/h3>\n\n\n\n<p>&#8220;Nous avons surmont\u00e9 les 15 kilom\u00e8tres jusqu&#8217;\u00e0 Manhouch en 9 heures. Sur la route, il y avait beaucoup de barrages routiers, des chars des fascistes russes. Il faisait tr\u00e8s froid, mais nous avons \u00e9conomis\u00e9 du carburant et n&#8217;avons pas mis le chauffage. J&#8217;ai interdit \u00e0 ma m\u00e8re de regarder par la fen\u00eatre et je lui ai dit de prier. Je n&#8217;ai jamais cru en Dieu, mais j&#8217;ai pri\u00e9 tout le long du chemin&#8221;.<\/p>\n\n\n\n<p>La jeune fille se souvient avec une sinc\u00e8re gratitude de la fa\u00e7on dont les infirmi\u00e8res \u00e0 Manhouch l&#8217;ont laiss\u00e9 passer la nuit et boire du th\u00e9 et du caf\u00e9 chauds avec ses compagnons dans la chambre d&#8217;h\u00f4pital. Le lendemain matin, les habitants de Marioupol sont partis \u00e0 Berdyansk.<\/p>\n\n\n\n<p>Dans le coffre de la voiture se trouvait le violon de la m\u00e8re de Daria. Lorsqu&#8217;elles \u00e9taient encore \u00e0 Marioupol, une femme est all\u00e9e secr\u00e8tement \u00e0 l&#8217;\u00e9cole de musique de la part de sa fille. Quand Dasha l&#8217;a appris, se souvient-elle, elle a beaucoup disput\u00e9 sa m\u00e8re, mais celle-ci \u00e9tait heureuse d&#8217;avoir pu amener son instrument. Pour cela, elles ont \u00e9t\u00e9 v\u00e9rifi\u00e9es \u00e0 tous les postes de contr\u00f4le, ils pensaient qu&#8217;il y avait une mitraillette dans le bo\u00eetier du violon.<\/p>\n\n\n\n<h3><strong><strong>&#8220;JE SUIS DEVENUE FOLLE ET JE SUIS ALL\u00c9E VOIR LES FASCISTES RUSSES&#8221;.<\/strong><\/strong><\/h3>\n\n\n\n<p>Vers Berdyansk, Dasha roulait \u00e0 une vitesse folle. Le carburant s&#8217;\u00e9puisait. La jeune fille a compris que si on peut toujours acheter de l&#8217;essence ou du gaz, elle ne trouvera pas de diesel, ce qui signifie qu&#8217;elle n&#8217;atteindra pas Zaporizhzhya.<\/p>\n\n\n\n<p>&#8220;J&#8217;ai vu qu&#8217;il y avait un char militaire appartenant aux fascistes russes. Je suis devenue folle, je suis all\u00e9e les voir et j&#8217;ai dit&nbsp;: &#8220;Donnez-moi du diesel&#8221;. Ils ont dit qu&#8217;ils n&#8217;en avaient pas, mais j&#8217;ai insist\u00e9, car tous leurs chars fonctionnent au diesel. Puis, ils ont dit que personne n&#8217;en donnera la journ\u00e9e, viens la nuit apr\u00e8s le couvre-feu. J&#8217;ai pris deux bidons et j&#8217;y suis all\u00e9e \u00e0 19h. Le gars qui m&#8217;a promis \u00e7a n&#8217;\u00e9tait pas l\u00e0. Les occupants ont dit que les chars \u00e9taient au coin de la rue.<\/p>\n\n\n\n<p>8 hommes en uniforme sont sortis en gilets pare-balles avec des grenades accroch\u00e9es et des fusils d&#8217;assaut. Ils \u00e9taient tous d&#8217;apparence slaves, sauf un. J&#8217;ai dit que j&#8217;\u00e9tais en voiture avec des filles et qu&#8217;on avait besoin de diesel pour partir. Ils m&#8217;ont offert de rester avec eux et ont promis d&#8217;aider. Ils nous ont demand\u00e9 pourquoi nous les traitions mal, parce qu&#8217;ils sont venus nous sauver. \u00c7a me d\u00e9goutait vraiment d&#8217;\u00e9couter leur discours, mais je savais qu&#8217;il fallait rester silencieux pour sauver des vies. J&#8217;ai \u00e9clat\u00e9 en sanglots et ils ont sorti un bidon de diesel de 20 litres. Ils m&#8217;ont \u00e9galement offert du th\u00e9, demand\u00e9 si j&#8217;avais un enfant, car ils peuvent donner du lait, du beurre, des biscuits. Je savais qu&#8217;il y avait beaucoup d&#8217;enfants dans le b\u00e2timent o\u00f9 nous nous sommes arr\u00eat\u00e9s et qu&#8217;il n&#8217;y avait pas de nourriture. Je leur ai dit de donner tout ce qu&#8217;ils pouvaient. Ils ont donn\u00e9 une \u00e9norme bo\u00eete de nourriture pour b\u00e9b\u00e9 et \u00e0 20 heures, je suis retourn\u00e9e chez les miens&#8221;.<\/p>\n\n\n\n<p>&#8220;\u00c0 Berdyansk, nous avons pris notre premi\u00e8re douche chaude. Je me tenais sous les jets d&#8217;eau chauds et je pleurais. Apr\u00e8s tout ce que tu as v\u00e9cu, tu commences \u00e0 appr\u00e9cier des choses qui peuvent te sembler insignifiantes. Quand quelqu&#8217;un a apport\u00e9 une cigarette et a offert de fumer \u00e0 trois, quand quelqu&#8217;un a apport\u00e9 un bonbon, quand quelqu&#8217;un nous a tenu la main.<\/p>\n\n\n\n<p>Sur le chemin vers Zaporizhzhya \u00e0 chaque poste de contr\u00f4le, les hommes \u00e9taient d\u00e9shabill\u00e9s, les occupants v\u00e9rifiaient les tatouages et les bleus des manches de fusils, passaient en revue tous les t\u00e9l\u00e9phones&nbsp;: les canaux Telegram et toutes les photos.<\/p>\n\n\n\n<p>&#8220;Quand nous sommes entr\u00e9s \u00e0 Zaporizhzhya, nous avons vu des drapeaux bleus et jaunes, nos militaires avec du scotch bleu. Je pleurais, je voulais sortir de la voiture et embrasser tout le monde. Quand tu es entre ces porcs pendant un mois, c&#8217;est une \u00e9motion incroyable de voir notre peuple&#8221;.<\/p>\n\n\n\n<h3><strong><strong>&#8220;IL FAUT AVOIR PEUR DES VIVANTS, PAS DES MORTS&#8221;<\/strong><\/strong><\/h3>\n\n\n\n<p>Je demande \u00e0 Dasha ce qui \u00e9tait le plus terrible pour elle. Pour une personne qui n&#8217;a presque pas vu les horreurs de la guerre en direct et qui ne conna\u00eet pas le son des bombes a\u00e9riennes, la r\u00e9ponse a \u00e9t\u00e9 inattendue&nbsp;:<\/p>\n\n\n\n<p>&#8220;Le pire, c&#8217;est quand l&#8217;avion vole. Tu n&#8217;iras nulle part. Tu vois ce qu&#8217;il peut faire. Le c\u0153ur s&#8217;arr\u00eate. Il faut avoir peur des vivants, pas des morts. Tu t&#8217;habitues aux morts. Oui, les cadavres sont d\u00e9sagr\u00e9ables. Ce que tu vois te rattrapes plus tard. Parce que tu commences \u00e0 t&#8217;en souvenir involontairement. Ces images peuvent t&#8217;emp\u00eacher de dormir. Mais il n&#8217;y a rien de plus effrayant que les avions. La plus grande peur est la peur de la mort.<\/p>\n\n\n\n<p>Aujourd&#8217;hui, je r\u00eave de Marioupol tr\u00e8s souvent. Et de la ville encore enti\u00e8re, et de la ville bombard\u00e9e : je cherche quelque chose, je cours quelque part. Parfois, on r\u00eave de la victoire et de notre retour \u00e0 Marioupol. C&#8217;\u00e9tait une tr\u00e8s belle ville, j&#8217;en garde beaucoup de souvenirs, des proches, de ma famille, de mes grands-parents, de mon p\u00e8re enterr\u00e9 \u00e0 Marioupol. Je veux vraiment rentrer \u00e0 la maison.<\/p>\n\n\n\n<p>Apr\u00e8s cela, j&#8217;ai commenc\u00e9 \u00e0 avoir des probl\u00e8mes psychologiques. Le premier tonnerre est une crise de col\u00e8re qui dure la moiti\u00e9 de la nuit, le son d&#8217;un avion m&#8217;a paralys\u00e9 dans la rue. Beaucoup de gens pensent qu&#8217;ils vont s&#8217;aider eux-m\u00eames, mais ce n&#8217;est souvent pas le cas. Le psychologue ne m&#8217;a pas aid\u00e9, je me suis tourn\u00e9 vers un psychiatre, j&#8217;ai stabilis\u00e9 mon \u00e9tat mental et maintenant, je me sens bien.<\/p>\n\n\n\n<p>Selon des donn\u00e9es non-officielles\u2063\u2063, en ao\u00fbt 2022 \u00e0 Marioupol, 87 000 morts ont \u00e9t\u00e9 document\u00e9s. Mais il y a encore des corps dans les cours, dans les fosses communes, des gens enterr\u00e9s vivants dans les sous-sols, sous le th\u00e9\u00e2tre de la ville, et pour certains, il ne reste m\u00eame plus de corps. C&#8217;est un habitant sur cinq de Marioupol. Je ne comprends pas comment j&#8217;ai surv\u00e9cu.&#8221;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" width=\"720\" height=\"1280\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg' viewBox%3D'0 0 720 1280'%2F%3E\" data-src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni.jpg\" alt=\"\" class=\"lazyload wp-image-218713\" data-srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni.jpg 720w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni-169x300.jpg 169w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni-576x1024.jpg 576w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni-265x471.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni-531x944.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/Dasha-z-kotom-Simboyu-na-Vinnychyni-608x1081.jpg 608w\" data-sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-right\"><strong>Ksenia Chokina<\/strong>,<strong>Uzhhorod<\/strong><br><strong>30.09.2022<\/strong><br><strong>Traduit de l\u2019ukrainien par Alexis Audonnet<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;On voit des gens qui sont encore en vie, bien qu&#8217;ils n&#8217;aient pas de t\u00eate ; on voit des soldats courir, alors qu&#8217;on leur a coup\u00e9 les deux pieds ; ils boitillent sur leurs moignons avec des \u00e9clats d&#8217;os qui d\u00e9passent jusqu&#8217;\u00e0 la br\u00e8che la plus proche ; un caporal a ramp\u00e9 deux kilom\u00e8tres sur [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/uacrisis.org\/fr\/u-mariupoli\">Plus<\/a><\/p>\n","protected":false},"author":6,"featured_media":220602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5889,33424],"tags":[32703,32785,7136,32782,32783,33044,7352,33425,33426,33427],"section":[709],"form":[33428],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol&quot; | UACRISIS.ORG<\/title>\n<meta name=\"description\" content=\"&quot;On voit des gens qui sont encore en vie, bien qu&#039;ils n&#039;aient pas de t\u00eate ; on voit des soldats courir, alors qu&#039;on leur a coup\u00e9 les deux pieds ; ils | Uacrisis.org\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uacrisis.org\/fr\/u-mariupoli\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol&quot; | UACRISIS.ORG\" \/>\n<meta property=\"og:description\" content=\"&quot;On voit des gens qui sont encore en vie, bien qu&#039;ils n&#039;aient pas de t\u00eate ; on voit des soldats courir, alors qu&#039;on leur a coup\u00e9 les deux pieds ; ils | Uacrisis.org\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uacrisis.org\/fr\/u-mariupoli\" \/>\n<meta property=\"og:site_name\" content=\"Uacrisis.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uacrisis\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T08:06:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-05T13:15:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uacrisis\" \/>\n<meta name=\"twitter:site\" content=\"@uacrisis\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol\" | UACRISIS.ORG","description":"\"On voit des gens qui sont encore en vie, bien qu'ils n'aient pas de t\u00eate ; on voit des soldats courir, alors qu'on leur a coup\u00e9 les deux pieds ; ils | Uacrisis.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uacrisis.org\/fr\/u-mariupoli","og_locale":"fr_FR","og_type":"article","og_title":"\"Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol\" | UACRISIS.ORG","og_description":"\"On voit des gens qui sont encore en vie, bien qu'ils n'aient pas de t\u00eate ; on voit des soldats courir, alors qu'on leur a coup\u00e9 les deux pieds ; ils | Uacrisis.org","og_url":"https:\/\/uacrisis.org\/fr\/u-mariupoli","og_site_name":"Uacrisis.org","article_publisher":"https:\/\/www.facebook.com\/uacrisis\/","article_published_time":"2022-10-24T08:06:26+00:00","article_modified_time":"2022-11-05T13:15:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@uacrisis","twitter_site":"@uacrisis","twitter_misc":{"\u00c9crit par":"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432","Dur\u00e9e de lecture est.":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/uacrisis.org\/uk\/#organization","name":"Ukraine crisis media center","url":"https:\/\/uacrisis.org\/uk\/","sameAs":["https:\/\/www.facebook.com\/uacrisis\/","http:\/\/youtube.com\/UACrisisMediaCenter","https:\/\/twitter.com\/uacrisis"],"logo":{"@type":"ImageObject","@id":"https:\/\/uacrisis.org\/uk\/#logo","inLanguage":"fr-FR","url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2019\/10\/header_logo-1.png","contentUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2019\/10\/header_logo-1.png","width":250,"height":90,"caption":"Ukraine crisis media center"},"image":{"@id":"https:\/\/uacrisis.org\/uk\/#logo"}},{"@type":"WebSite","@id":"https:\/\/uacrisis.org\/uk\/#website","url":"https:\/\/uacrisis.org\/uk\/","name":"Uacrisis.org","description":"Ukraine crisis media center","publisher":{"@id":"https:\/\/uacrisis.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uacrisis.org\/uk\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#primaryimage","inLanguage":"fr-FR","url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/2.png","contentUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/2.png","width":1280,"height":720},{"@type":"WebPage","@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#webpage","url":"https:\/\/uacrisis.org\/fr\/u-mariupoli","name":"\"Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol\" | UACRISIS.ORG","isPartOf":{"@id":"https:\/\/uacrisis.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#primaryimage"},"datePublished":"2022-10-24T08:06:26+00:00","dateModified":"2022-11-05T13:15:37+00:00","description":"\"On voit des gens qui sont encore en vie, bien qu'ils n'aient pas de t\u00eate ; on voit des soldats courir, alors qu'on leur a coup\u00e9 les deux pieds ; ils | Uacrisis.org","breadcrumb":{"@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uacrisis.org\/fr\/u-mariupoli"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/uacrisis.org\/fr"},{"@type":"ListItem","position":2,"name":"&#8220;Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol&#8221;"}]},{"@type":"Article","@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#article","isPartOf":{"@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#webpage"},"author":{"@id":"https:\/\/uacrisis.org\/uk\/#\/schema\/person\/1a3a3a8e26023caf8adb4e015be5b695"},"headline":"&#8220;Je marchais entre les cadavres et recueillais les parties de corps humains \u00e0 Marioupol&#8221;","datePublished":"2022-10-24T08:06:26+00:00","dateModified":"2022-11-05T13:15:37+00:00","mainEntityOfPage":{"@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#webpage"},"wordCount":4401,"publisher":{"@id":"https:\/\/uacrisis.org\/uk\/#organization"},"image":{"@id":"https:\/\/uacrisis.org\/fr\/u-mariupoli#primaryimage"},"thumbnailUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2022\/10\/2.png","keywords":["\u00eatre r\u00e9silient","guerre","Russie","stop Putin","stop Russia","UCMC","Ukraine","Voix des r\u00e9gions","\u041c\u0430\u0440\u0456\u0443\u043f\u043e\u043b\u044c","\u0423\u043a\u0440\u0430\u0457\u043d\u0430 \u043d\u0435\u0441\u043a\u043e\u0440\u0435\u043d\u0438\u0445"],"articleSection":["La soci\u00e9t\u00e9","Voix des r\u00e9gions"],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/uacrisis.org\/uk\/#\/schema\/person\/1a3a3a8e26023caf8adb4e015be5b695","name":"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/219357"}],"collection":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/comments?post=219357"}],"version-history":[{"count":3,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/219357\/revisions"}],"predecessor-version":[{"id":220608,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/219357\/revisions\/220608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/media\/220602"}],"wp:attachment":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/media?parent=219357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/categories?post=219357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/tags?post=219357"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/section?post=219357"},{"taxonomy":"form","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/form?post=219357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}