{"id":232874,"date":"2023-01-27T12:35:24","date_gmt":"2023-01-27T10:35:24","guid":{"rendered":"https:\/\/uacrisis.org\/day-337"},"modified":"2023-01-27T12:44:49","modified_gmt":"2023-01-27T10:44:49","slug":"day-337","status":"publish","type":"post","link":"https:\/\/uacrisis.org\/fr\/day-337","title":{"rendered":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#8217;assaut de Vouhledar"},"content":{"rendered":"\n<h3><strong><strong>Nouvelle attaque de missile russe<\/strong><\/strong><\/h3>\n\n\n\n<p>Dans la matin\u00e9e, une alerte a\u00e9rienne a \u00e9t\u00e9 annonc\u00e9e dans toute l&#8217;Ukraine, elle a dur\u00e9 environ quatre heures, jusqu&#8217;\u00e0 12h08. La nuit, la Russie a attaqu\u00e9 l&#8217;Ukraine avec des drones iraniens, tous les 24 ont \u00e9t\u00e9 abattus, dont environ 15 dans le ciel au-dessus de Kyiv.<\/p>\n\n\n\n<p>La d\u00e9fense a\u00e9rienne a abattu 47 missiles sur 55, des d\u00e9g\u00e2ts dans 11 r\u00e9gions, des installations \u00e9nerg\u00e9tiques ont \u00e9t\u00e9 endommag\u00e9es, 11 d\u00e9c\u00e8s sont connus. La Russie a lanc\u00e9 une nouvelle attaque massive contre l&#8217;Ukraine : apr\u00e8s des frappes nocturnes de drones iraniens, le matin du 26 janvier, la Russie a tir\u00e9 des missiles de croisi\u00e8re sur Kyiv et d&#8217;autres r\u00e9gions d&#8217;Ukraine. Aujourd&#8217;hui, dans la premi\u00e8re moiti\u00e9 de la journ\u00e9e, selon les forces arm\u00e9es, la Russie a lanc\u00e9 55 missiles de croisi\u00e8re, les forces de d\u00e9fense a\u00e9rienne en ont abattu 47. Les lancements provenaient d&#8217;avions et de navires Tu-95, Su-35, MiG-31K en mer Noire. Parmi les missiles figurent les missiles X-101, X-555, X-47 Kinzhal, Kalibr, ainsi que les missiles guid\u00e9s dans les airs X-59.<\/p>\n\n\n\n<p>Selon le Minist\u00e8re ukrainien des situations d&#8217;urgence, \u00e0 15h00, 11 personnes sont mortes et 11 ont \u00e9t\u00e9 bless\u00e9es. 20 missiles de croisi\u00e8re ont \u00e9t\u00e9 abattus \u00e0 l&#8217;approche de Kyiv et au-dessus de la capitale.<\/p>\n\n\n\n<p>Des frappes ont \u00e9t\u00e9 confirm\u00e9es dans les r\u00e9gions suivantes : r\u00e9gion d&#8217;Odessa \u2014 deux installations \u00e9nerg\u00e9tiques ont \u00e9t\u00e9 endommag\u00e9es, il n&#8217;y a pas eu de victimes ; R\u00e9gion de Vinnytsia &#8211; il n&#8217;y a pas eu de victimes, il n&#8217;y a actuellement aucune information sur le lieu de la frappe; R\u00e9gion de Kyiv &#8211; les Russes ont frapp\u00e9 une installation \u00e9nerg\u00e9tique, il n&#8217;y a pas eu de victimes, des infrastructures civiles ont \u00e9t\u00e9 endommag\u00e9es (maisons priv\u00e9es, immeubles, voitures de r\u00e9sidents locaux &#8211; nous parlons de fen\u00eatres bris\u00e9es, de toits et de fa\u00e7ades de b\u00e2timents endommag\u00e9s).<\/p>\n\n\n\n<p>Kyiv &#8211; une explosion dans la r\u00e9gion de Dnipro, une partie du missile est \u00e9galement tomb\u00e9e dans le district Holosiivskyi (un homme de 55 ans est d\u00e9c\u00e9d\u00e9, deux personnes ont \u00e9t\u00e9 hospitalis\u00e9es), toutes les infrastructures de la capitale fonctionnent normalement.<\/p>\n\n\n\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-none\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":true,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":false,\"autoPlay\":false,\"imagesLoaded\":true,\"contain\":false,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a56cfbf7e984\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a.jpeg\" data-caption=\"\u00a9 t.me\/andrii_nebytov\"><img width=\"1036\" height=\"648\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a.jpeg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a.jpeg 1036w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-300x188.jpeg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-1024x640.jpeg 1024w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-768x480.jpeg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-265x166.jpeg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-531x332.jpeg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-608x380.jpeg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/91cc5c4ce7d5f782c5e36cf94df9b50a-758x474.jpeg 758w\" sizes=\"(max-width: 1036px) 100vw, 1036px\" \/><span>\u00a9 t.me\/andrii_nebytov<\/span><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1.jpg\" data-caption=\"Kids stand next to a crater left by a Russian military strike, amid Russia&#039;s attack on Ukraine, in the town of Hlevakha, outside Kyiv, Ukraine January 26, 2023.  REUTERS\/Valentyn Ogirenko\"><img width=\"830\" height=\"500\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1.jpg 830w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-300x181.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-768x463.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-265x160.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-531x320.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-608x366.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/2023-01-26T145539Z_1923215326_RC2BYY9NVOSC_RTRMADP_3_UKRAINE-CRISIS-ATTACKS-KYIV-REGION-830x500-1-758x457.jpg 758w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><span>Kids stand next to a crater left by a Russian military strike, amid Russia's attack on Ukraine, in the town of Hlevakha, outside Kyiv, Ukraine January 26, 2023.  REUTERS\/Valentyn Ogirenko<\/span><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f.jpeg\" data-caption=\"\u00a9 EPA\/UPG\"><img width=\"1000\" height=\"646\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f.jpeg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f.jpeg 1000w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-300x194.jpeg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-768x496.jpeg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-265x171.jpeg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-531x343.jpeg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-608x393.jpeg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/63d2983ccbf3f-758x490.jpeg 758w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><span>\u00a9 EPA\/UPG<\/span><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1.jpg\" data-caption=\"\u00a9 SESU\"><img width=\"871\" height=\"461\" src=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1.jpg\" class=\"\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1.jpg 871w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-300x159.jpg 300w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-768x406.jpg 768w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-265x140.jpg 265w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-531x281.jpg 531w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-608x322.jpg 608w, https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/Screenshot_1-758x401.jpg 758w\" sizes=\"(max-width: 871px) 100vw, 871px\" \/><span>\u00a9 SESU<\/span><\/a><\/div><\/div><\/div><script id=\"su_image_carousel_6a56cfbf7e984_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a56cfbf7e984\"))}, 0);}var su_image_carousel_6a56cfbf7e984_script=document.getElementById(\"su_image_carousel_6a56cfbf7e984_script\");if(su_image_carousel_6a56cfbf7e984_script){su_image_carousel_6a56cfbf7e984_script.parentNode.removeChild(su_image_carousel_6a56cfbf7e984_script);}<\/script>\n\n\n\n<h3><strong><strong>Les troupes russes ont commenc\u00e9 un assaut sur Vouhledar<\/strong><\/strong><\/h3>\n\n\n\n<p>Vouhledar est d&#8217;une importance capitale pour la F\u00e9d\u00e9ration de Russie, c&#8217;est un point de communication strat\u00e9giquement important au sud du Donbass, une fronti\u00e8re pour le d\u00e9ploiement de la future offensive ukrainienne sur le corridor de Crim\u00e9e. La prise de Vouhledar am\u00e9liorera consid\u00e9rablement la position strat\u00e9gique de l&#8217;arm\u00e9e russe dans le Donbass, et permettra d&#8217;approfondir la d\u00e9fense.<\/p>\n\n\n\n<p>L&#8217;objectif du commandement russe dans la campagne de 2023 est de capturer tout le Donbass ou d&#8217;\u00e9loigner notre arm\u00e9e du couloir de Crim\u00e9e.<\/p>\n\n\n\n<p>Pour capturer Vouhledar, les Russes ont concentr\u00e9 leurs meilleures forces &#8211; des brigades de marines et de troupes a\u00e9roport\u00e9es, des stocks de munitions.<\/p>\n\n\n\n<h3><strong><strong>R\u00e9gion de Kharkiv : la vie apr\u00e8s la lib\u00e9ration. Ukraine in Flames \u2116322<\/strong><\/strong><\/h3>\n\n\n\n<p>La r\u00e9gion de Kharkiv a \u00e9t\u00e9 sous occupation russe pendant pr\u00e8s de 5 mois. D\u00e9but septembre 2022, lors d&#8217;une contre-offensive, les Ukrainiens ont repris la majeure partie de la r\u00e9gion de Kharkiv, lorsque les troupes ukrainiennes ont pris le contr\u00f4le des villes strat\u00e9giques de Koupyansk, Izyoum et Balakliya, zones critiques pour les lignes d&#8217;approvisionnement et la logistique russes. Regardez Ukraine in Flames #322 pour savoir \u00e0 quoi ressemble la vie actuelle dans ces villes lib\u00e9r\u00e9es et comment l&#8217;Ukraine reconstruit lentement et reconstruit les infrastructures d\u00e9truites par les occupants russes.<\/p>\n\n\n\n<p><strong>Invit\u00e9s&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Nataliya Kovalenko, b\u00e9n\u00e9vole de l&#8217;ONG &#8220;URSA&#8221;, coordinatrice du Centre de pr\u00e9paration civile de Kharkiv (Serhiy Prytula Charitable Foundation)<\/li><li>Serhii Ovsyannikov, co-coordinateur du centre logistique des volontaires &#8220;Hub Vokzal&#8221;, responsable de l&#8217;ONG &#8220;Kupyansk &#8211; notre maison natale&#8221;<\/li><li>Yuriy Larin, journaliste<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div id=\"g1-fluid-wrapper-counter-1\" class=\"g1-fluid-wrapper \" style=\"width:662px;\" data-g1-fluid-width=\"662\" data-g1-fluid-height=\"372\">\n\t       <div class=\"g1-fluid-wrapper-inner\" style=\"padding-bottom:56.19335347432%;\">\n\t       <div class=\"mace-youtube\" data-mace-video=\"https:\/\/www.youtube.com\/embed\/f2g7XSPwqbI?showinfo=0&#038;rel=1&#038;ytp-pause-overlay=1&#038;autoplay=1&#038;enablejsapi=1\" data-mace-video-thumb=\"https:\/\/img.youtube.com\/vi\/f2g7XSPwqbI\/hqdefault.jpg\"><div class=\"mace-play-button\"><\/div><\/div>\n\t       <\/div>\n\t       <\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nouvelle attaque de missile russe Dans la matin\u00e9e, une alerte a\u00e9rienne a \u00e9t\u00e9 annonc\u00e9e dans toute l&#8217;Ukraine, elle a dur\u00e9 environ quatre heures, jusqu&#8217;\u00e0 12h08. La nuit, la Russie a attaqu\u00e9 l&#8217;Ukraine avec des drones iraniens, tous les 24 ont \u00e9t\u00e9 abattus, dont environ 15 dans le ciel au-dessus de Kyiv. La d\u00e9fense a\u00e9rienne a [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/uacrisis.org\/fr\/day-337\">Plus<\/a><\/p>\n","protected":false},"author":6,"featured_media":232875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[625,5889],"tags":[33051,32703,8912,32785,33053,33411,7136,32781,32782,32783,33044,7352,33592],"section":[744],"form":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#039;assaut de Vouhledar | UACRISIS.ORG<\/title>\n<meta name=\"description\" content=\"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#039;assaut de Vouhledar | Uacrisis.org\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uacrisis.org\/fr\/day-337\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#039;assaut de Vouhledar | UACRISIS.ORG\" \/>\n<meta property=\"og:description\" content=\"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#039;assaut de Vouhledar | Uacrisis.org\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uacrisis.org\/fr\/day-337\" \/>\n<meta property=\"og:site_name\" content=\"Uacrisis.org\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uacrisis\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T10:35:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T10:44:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/337-FR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uacrisis\" \/>\n<meta name=\"twitter:site\" content=\"@uacrisis\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | UACRISIS.ORG","description":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | Uacrisis.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uacrisis.org\/fr\/day-337","og_locale":"fr_FR","og_type":"article","og_title":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | UACRISIS.ORG","og_description":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | Uacrisis.org","og_url":"https:\/\/uacrisis.org\/fr\/day-337","og_site_name":"Uacrisis.org","article_publisher":"https:\/\/www.facebook.com\/uacrisis\/","article_published_time":"2023-01-27T10:35:24+00:00","article_modified_time":"2023-01-27T10:44:49+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/337-FR.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@uacrisis","twitter_site":"@uacrisis","twitter_misc":{"\u00c9crit par":"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/uacrisis.org\/uk\/#organization","name":"Ukraine crisis media center","url":"https:\/\/uacrisis.org\/uk\/","sameAs":["https:\/\/www.facebook.com\/uacrisis\/","http:\/\/youtube.com\/UACrisisMediaCenter","https:\/\/twitter.com\/uacrisis"],"logo":{"@type":"ImageObject","@id":"https:\/\/uacrisis.org\/uk\/#logo","inLanguage":"fr-FR","url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2019\/10\/header_logo-1.png","contentUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2019\/10\/header_logo-1.png","width":250,"height":90,"caption":"Ukraine crisis media center"},"image":{"@id":"https:\/\/uacrisis.org\/uk\/#logo"}},{"@type":"WebSite","@id":"https:\/\/uacrisis.org\/uk\/#website","url":"https:\/\/uacrisis.org\/uk\/","name":"Uacrisis.org","description":"Ukraine crisis media center","publisher":{"@id":"https:\/\/uacrisis.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uacrisis.org\/uk\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/uacrisis.org\/fr\/day-337#primaryimage","inLanguage":"fr-FR","url":"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/337-FR.jpg","contentUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/337-FR.jpg","width":1200,"height":675},{"@type":"WebPage","@id":"https:\/\/uacrisis.org\/fr\/day-337#webpage","url":"https:\/\/uacrisis.org\/fr\/day-337","name":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | UACRISIS.ORG","isPartOf":{"@id":"https:\/\/uacrisis.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uacrisis.org\/fr\/day-337#primaryimage"},"datePublished":"2023-01-27T10:35:24+00:00","dateModified":"2023-01-27T10:44:49+00:00","description":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l'assaut de Vouhledar | Uacrisis.org","breadcrumb":{"@id":"https:\/\/uacrisis.org\/fr\/day-337#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uacrisis.org\/fr\/day-337"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uacrisis.org\/fr\/day-337#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/uacrisis.org\/fr"},{"@type":"ListItem","position":2,"name":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#8217;assaut de Vouhledar"}]},{"@type":"Article","@id":"https:\/\/uacrisis.org\/fr\/day-337#article","isPartOf":{"@id":"https:\/\/uacrisis.org\/fr\/day-337#webpage"},"author":{"@id":"https:\/\/uacrisis.org\/uk\/#\/schema\/person\/1a3a3a8e26023caf8adb4e015be5b695"},"headline":"Jour 337 de r\u00e9sistance : une attaque massive de missile, l&#8217;assaut de Vouhledar","datePublished":"2023-01-27T10:35:24+00:00","dateModified":"2023-01-27T10:44:49+00:00","mainEntityOfPage":{"@id":"https:\/\/uacrisis.org\/fr\/day-337#webpage"},"wordCount":703,"publisher":{"@id":"https:\/\/uacrisis.org\/uk\/#organization"},"image":{"@id":"https:\/\/uacrisis.org\/fr\/day-337#primaryimage"},"thumbnailUrl":"https:\/\/uacrisis.org\/wp-content\/uploads\/2023\/01\/337-FR.jpg","keywords":["ArmUkraineNow","\u00eatre r\u00e9silient","Forces arm\u00e9es ukrainiennes","guerre","Photo","Russian War Crimes","Russie","Stand with Ukraine","stop Putin","stop Russia","UCMC","Ukraine","video"],"articleSection":["la s\u00e9curit\u00e9","La soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/uacrisis.org\/uk\/#\/schema\/person\/1a3a3a8e26023caf8adb4e015be5b695","name":"\u0414\u043c\u0438\u0442\u0440\u043e \u0412\u0430\u0441\u0438\u043b\u044c\u0454\u0432"}]}},"wps_subtitle":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/232874"}],"collection":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/comments?post=232874"}],"version-history":[{"count":1,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/232874\/revisions"}],"predecessor-version":[{"id":232881,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/posts\/232874\/revisions\/232881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/media\/232875"}],"wp:attachment":[{"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/media?parent=232874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/categories?post=232874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/tags?post=232874"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/section?post=232874"},{"taxonomy":"form","embeddable":true,"href":"https:\/\/uacrisis.org\/fr\/wp-json\/wp\/v2\/form?post=232874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}